{"id":134,"date":"2020-06-16T13:27:46","date_gmt":"2020-06-16T13:27:46","guid":{"rendered":"https:\/\/jacoblaw.adv.br\/?p=134"},"modified":"2020-10-13T19:47:42","modified_gmt":"2020-10-13T19:47:42","slug":"novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso","status":"publish","type":"post","link":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/","title":{"rendered":"New work relationships: what does technology and innovation have to do with it?"},"content":{"rendered":"<p>Vivemos uma \u00e9poca com o maior n\u00famero de inova\u00e7\u00f5es tecnol\u00f3gicas da hist\u00f3ria da humanidade. Isso trouxe mudan\u00e7as significativas na din\u00e2mica da sociedade e, claro, nas rela\u00e7\u00f5es de trabalho.<\/p>\n\n\n\n<p>\u00c0&nbsp; medida que novas e inovadoras tecnologias v\u00e3o surgindo, o conceito de carreira vai se tornando mais din\u00e2mico tamb\u00e9m. Aquela velha pergunta \u201cqual \u00e9 a sua profiss\u00e3o?\u201d j\u00e1 n\u00e3o faz tanto sentido agora, diante das demandas plurais do mercado.<\/p>\n\n\n\n<p>Desde empresas de gerenciamento de tr\u00e1fego de sites at\u00e9 <a href=\"https:\/\/www.youtube.com\/watch?v=Z0y2MDUlt_4\">adolescentes ganhando a vida como <em>social media<\/em> de v\u00e1rios neg\u00f3cios na internet<\/a>, estamos vendo um mundo de empreendedores empoderados e trabalhadores digitais que n\u00e3o se preocupam tanto com a carteira assinada.<\/p>\n\n\n\n<p>Os <em>millennials, <\/em>gera\u00e7\u00e3o que hoje t\u00eam entre 18 e 35 anos<em>,<\/em><a href=\"https:\/\/epocanegocios.globo.com\/Empresa\/noticia\/2019\/09\/millennials-ja-sao-maioria-da-populacao-do-pais-e-70-da-forca-de-trabalho.html\"><em> <\/em>j\u00e1 s\u00e3o a maioria da popula\u00e7\u00e3o<\/a><em> <\/em>e est\u00e3o dispostos a terem pequenos cortes de sal\u00e1rio se puderem ter flexibilidade.<\/p>\n\n\n\n<p>Essa flexibilidade pode proporcionar tempo e dar espa\u00e7o para novos projetos.<\/p>\n\n\n\n<p>Em outras palavras, aquele posto de trabalho convencional no escrit\u00f3rio da empresa, com sal\u00e1rio fixo e, em regra, por prazo indeterminado, est\u00e1 sendo substitu\u00eddo por <strong>rela\u00e7\u00f5es de trabalho mais din\u00e2micas e criativas<\/strong>, avaliadas por produtividade e n\u00e3o necessariamente pela jornada de trabalho convencional.<\/p>\n\n\n\n<p>Isso exige regras de trabalho um pouco mais flex\u00edveis; a legisla\u00e7\u00e3o brasileira j\u00e1 permite estrutura\u00e7\u00f5es de trabalho mais modernas e din\u00e2micas com seguran\u00e7a, desde que planejada e executada com a devida compliance.<\/p>\n\n\n\n<p>A pergunta \u00e9: <strong>sua empresa est\u00e1 preparada para se adaptar \u00e0 essa nova economia e rela\u00e7\u00f5es de trabalho?<\/strong><\/p>\n\n\n\n<p><strong>E voc\u00ea, &#8220;empregado&#8221;, j\u00e1 percebeu o campo f\u00e9rtil de novas oportunidades de empreender fazendo justamente aquilo que voc\u00ea j\u00e1 vinha fazendo sobre as amarras de um contrato de trabalho?<\/strong><\/p>\n\n\n\n<p>Mais ainda, a oportunidade de oferecer um servi\u00e7o mais otimizado, colaborativo e produtivo para diferentes clientes e n\u00e3o mais para um \u00fanico &#8220;empregador&#8221;?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trabalho remoto<\/h2>\n\n\n\n<p><br>Se pararmos para observar, h\u00e1 uma verdadeira crise da figura cl\u00e1ssica do trabalho das 8h \u00e0s 18h, principalmente com essa nova realidade econ\u00f4mica, mundial e tecnol\u00f3gica.<\/p>\n\n\n\n<p>Essa flexibiliza\u00e7\u00e3o dos atuais modos de trabalho faz parte de um processo maior de flexibiliza\u00e7\u00e3o das regras trabalhistas, composto por um conjunto de medidas capazes de adequar as novas rela\u00e7\u00f5es de trabalho \u00e0s mudan\u00e7as decorrentes de diversos fatores, como a pr\u00f3pria <strong>inova\u00e7\u00e3o tecnol\u00f3gica<\/strong>.<\/p>\n\n\n\n<p>A tecnologia influenciou a flexibiliza\u00e7\u00e3o do modo de trabalho, pois permitiu que os colaboradores estivessem conectados \u00e0 empresa, sem a necessidade da presen\u00e7a f\u00edsica, mas apenas virtual.<\/p>\n\n\n\n<p>Se n\u00e3o h\u00e1 a necessidade de disponibilizar uma sala para o colaborador desenvolver a sua fun\u00e7\u00e3o, e ele pode trabalhar no conforto de sua casa, por que obrig\u00e1-lo a comparecer na empresa?<\/p>\n\n\n\n<p>O trabalho remoto, ali\u00e1s, vem sendo a resposta empresarial para a manuten\u00e7\u00e3o do processo produtivo em diversos ramos de neg\u00f3cio, diante do isolamento social.<\/p>\n\n\n\n<p>Essa nova forma de trabalho precisa continuar evoluindo, tanto em termos de neg\u00f3cio quanto em termos legislativos, a fim de oferecer \u00e0s empresas mecanismos jur\u00eddicos que possibilitem o ajuste da produ\u00e7\u00e3o e das rela\u00e7\u00f5es de trabalho \u00e0s r\u00e1pidas transforma\u00e7\u00f5es da economia.<\/p>\n\n\n\n<p>J\u00e1 observamos um importante avan\u00e7o com a reforma trabalhista (Lei 13.467\/17), a qual flexibilizou a forma de contratar e negociar entre empregadores e empregados, autorizando, por exemplo, a terceiriza\u00e7\u00e3o da pr\u00f3pria atividade fim da empresa, regra esta cuja&nbsp; constitucionalidade foi recentemente reconhecida pelo <a href=\"http:\/\/redir.stf.jus.br\/paginadorpub\/paginador.jsp?docTP=TP&amp;docID=750817537\">Supremo Tribunal Federal.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Economia compartilhada<\/h2>\n\n\n\n<p>A economia compartilhada j\u00e1 \u00e9 uma tend\u00eancia mundial.<\/p>\n\n\n\n<p>Trata-se de um modelo de mercado h\u00edbrido de trocas <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Peer-to-peer\"><em>peer-to-peer<\/em><\/a>, no qual o acesso a bens e servi\u00e7os s\u00e3o com base em processos colaborativos e de <strong>uso comum.<\/strong><\/p>\n\n\n\n<p>Em outras palavras, \u00e9 uma maneira de fazer mais com menos e aproveitar ao m\u00e1ximo os recursos, sejam ambientais, estruturais ou tecnol\u00f3gicos.&nbsp;<\/p>\n\n\n\n<p>Um exemplo cl\u00e1ssico de economia compartilhada \u00e9 o <a href=\"https:\/\/www.airbnb.com.br\/\">Airbnb<\/a>. O propriet\u00e1rio de algum im\u00f3vel que tenha um quarto dispon\u00edvel em seu apartamento pode alug\u00e1-lo a outra pessoa dentro da plataforma e monetizar esse espa\u00e7o que antes estava inutilizado.<\/p>\n\n\n\n<p>No Brasil, al\u00e9m do Airbnb, outras plataformas digitais de economia compartilhada ganham destaque, como a Uber, 99Taxis, DogHero, Netflix e BlaBlaCar.&nbsp;<\/p>\n\n\n\n<p>Existe um avan\u00e7o natural para uma economia mais empreendedora e que aproveita melhor os recursos, mas tamb\u00e9m aponta para a necessidade de uma legisla\u00e7\u00e3o que contemple a inova\u00e7\u00e3o e a compatibilize \u00e0 vida cotidiana.<\/p>\n\n\n\n<p>A cria\u00e7\u00e3o da Uber, por exemplo, provocou uma obrigatoriedade de <a href=\"https:\/\/legis.senado.leg.br\/norma\/26382098\/publicacao\/26382164\">mudan\u00e7a na legisla\u00e7\u00e3o<\/a> relativa ao transporte remunerado privado individual de passageiros.<\/p>\n\n\n\n<p>Esses s\u00e3o apenas alguns exemplos. Outras ideias inovadoras ainda est\u00e3o por vir, e dever\u00e3o vir por uma quest\u00e3o tanto de adequa\u00e7\u00e3o \u00e0s novas m\u00e9tricas de presta\u00e7\u00e3o de servi\u00e7o e consumo quanto de inova\u00e7\u00e3o constante, a qual exigir\u00e1 um time de experts que seguramente n\u00e3o ser\u00e3o contratados segundo o modelo at\u00e9 ent\u00e3o posto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trabalho colaborativo<\/h2>\n\n\n\n<p>A inova\u00e7\u00e3o n\u00e3o est\u00e1 mais relacionada com genialidade solit\u00e1ria, mas sim com genialidade coletiva.<\/p>\n\n\n\n<p>Para inventar &#8211; ou reinventar &#8211; um futuro melhor, \u00e9 necess\u00e1rio criar o espa\u00e7o onde as por\u00e7\u00f5es de genialidade de todos possam ser aproveitadas e transformadas em obras de genialidade coletiva.<\/p>\n\n\n\n<p>No trabalho coletivo, as solu\u00e7\u00f5es s\u00e3o focadas na conectividade entre as pessoas, de modo a simplificar o desenvolvimento e compartilhamento de ideias, arquivos e informa\u00e7\u00f5es \u00fateis.<\/p>\n\n\n\n<p>Tudo o que acontece no ambiente corporativo da sua empresa fica armazenado em uma <a href=\"https:\/\/gsuite.google.com.br\/intl\/pt-BR\/features\/\">plataforma de colabora\u00e7\u00e3o na nuvem<\/a>, acess\u00edvel a todos, de qualquer lugar que tenha uma conex\u00e3o com a internet.<\/p>\n\n\n\n<p>Assim, a organiza\u00e7\u00e3o fica mais horizontal, e a tomada de decis\u00f5es fica delegada \u00e0 uma rede de equipes din\u00e2mica e eficaz.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Times com mais diversidade<\/h2>\n\n\n\n<p>Com a possibilidade de contrata\u00e7\u00e3o remota e independente de curr\u00edculos tradicionais, as portas se abrem para a <strong>diversidade<\/strong>.<\/p>\n\n\n\n<p>Mentes brilhantes de todo o mundo podem trabalhar em colabora\u00e7\u00e3o para criar projetos inovadores ou desenvolver atividades espec\u00edficas dentro de uma empresa.<\/p>\n\n\n\n<p>Em sua palestra no TED, intitulada \u201c<a href=\"https:\/\/www.ted.com\/talks\/rocio_lorenzo_want_a_more_innovative_company_hire_more_women\/transcript\"><em>How diversity makes teams more innovative<\/em><\/a>\u201d, <a href=\"https:\/\/www.bcg.com\/pt-br\/about\/people\/experts\/rocio-lorenzo.aspx\">Roc\u00edo Lorenzo<\/a>, uma consultora de transforma\u00e7\u00e3o de neg\u00f3cios em tempos de ruptura digital e diretora administrativa do <em>The Boston Consulting Group \u2013 BCG<\/em>, fala sobre uma pesquisa feita com empresas de diferentes pa\u00edses.<\/p>\n\n\n\n<p>Segundo ela, as pesquisas mostraram que <strong>as empresas que apostam em diversidade s\u00e3o, simplesmente, mais inovadoras.<\/strong><\/p>\n\n\n\n<p>Al\u00e9m disso, empresas mais inovadoras t\u00eam times mais heterog\u00eaneos tamb\u00e9m.<\/p>\n\n\n\n<p>Essa possibilidade de ter colaboradores de diferentes lugares, por exemplo, ainda pode suscitar d\u00favidas na interpreta\u00e7\u00e3o do ordenamento jur\u00eddico.<\/p>\n\n\n\n<p>Em um mundo globalizado, qual seria a melhor forma de proteger o trabalhador que exerce sua atividade fora do seu pa\u00eds de origem? Qual legisla\u00e7\u00e3o deve ser aplicada em casos de conflitos de normas entre um pa\u00eds e outro? E nos casos de contratos internacionais de trabalho fracionados?<\/p>\n\n\n\n<p>As solu\u00e7\u00f5es destes problemas e muitos outros que ainda v\u00e3o surgir dependem de profissionais que pensem de forma disruptiva e global, a fim de preservar ao m\u00e1ximo a sa\u00fade da empresa e as atividades de seus colaboradores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\n\n\n\n<p>Est\u00e1 muito clara a integra\u00e7\u00e3o do mundo. Os neg\u00f3cios e o pr\u00f3prio direito dever\u00e3o ser estruturados segundo a nova economia.<\/p>\n\n\n\n<p>A velocidade dessas transforma\u00e7\u00f5es tecnol\u00f3gicas, claro, \u00e9 muito superior \u00e0 capacidade do Estado legislar sobre as incont\u00e1veis e imprevis\u00edveis situa\u00e7\u00f5es do cotidiano digital, mas \u00e9 importante que sua empresa conhe\u00e7a melhor o atual cen\u00e1rio e consiga se adaptar \u00e0 essa nova economia.<\/p>\n\n\n\n<p>Precisamos dar condi\u00e7\u00f5es para o Brasil se tornar um polo de desenvolvimento de tecnologia e recebimento de financiamentos, novos neg\u00f3cios e pessoas.<\/p>\n\n\n\n<p>O debate \u00e9 desafiador, mas \u00e9 necess\u00e1rio preparar o terreno para que o sistema jur\u00eddico brasileiro se adapte ao mundo exponencialmente disruptivo de forma equilibrada e justa.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vivemos uma \u00e9poca com o maior n\u00famero de inova\u00e7\u00f5es tecnol\u00f3gicas da hist\u00f3ria da humanidade. Isso trouxe mudan\u00e7as significativas na din\u00e2mica da sociedade e, claro, nas rela\u00e7\u00f5es de trabalho. \u00c0&nbsp; medida que novas e inovadoras tecnologias v\u00e3o surgindo, o conceito de carreira vai se tornando mais din\u00e2mico tamb\u00e9m. Aquela velha pergunta \u201cqual \u00e9 a sua profiss\u00e3o?\u201d&hellip;&nbsp;<a href=\"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">New work relationships: what does technology and innovation have to do with it?<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,11,5,10],"tags":[18,14,16,17],"class_list":["post-134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-digital","category-negocios-digitais","category-tranformacao-digital","category-tirbutacao-digital","tag-inovacao","tag-negocios-digitais","tag-novas-relacoes-de-trabalho","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso? - Jacob Law<\/title>\n<meta name=\"description\" content=\"\u00c0 medida que novas e inovadoras tecnologias v\u00e3o evoluindo as novas rela\u00e7\u00f5es de trabalho se tornam mais din\u00e2micas e instant\u00e2neas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso? - Jacob Law\" \/>\n<meta property=\"og:description\" content=\"\u00c0 medida que novas e inovadoras tecnologias v\u00e3o evoluindo as novas rela\u00e7\u00f5es de trabalho se tornam mais din\u00e2micas e instant\u00e2neas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/\" \/>\n<meta property=\"og:site_name\" content=\"Jacob Law\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-16T13:27:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-13T19:47:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jacoblaw.adv.br\/wp-content\/uploads\/2020\/10\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/\"},\"author\":{\"name\":\"Eduardo\",\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/#\\\/schema\\\/person\\\/37f9a3bf0b21ecb1ab4f89d49225b2a7\"},\"headline\":\"Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso?\",\"datePublished\":\"2020-06-16T13:27:46+00:00\",\"dateModified\":\"2020-10-13T19:47:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/\"},\"wordCount\":1368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jacoblaw.adv.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_.png\",\"keywords\":[\"inova\u00e7\u00e3o\",\"neg\u00f3cios digitais\",\"novas rela\u00e7\u00f5es de trabalho\",\"tecnologia\"],\"articleSection\":[\"Mundo Digital\",\"Neg\u00f3cios Digitais\",\"Transforma\u00e7\u00e3o Digital\",\"Tributa\u00e7\u00e3o Digital\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/\",\"url\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/\",\"name\":\"Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso? - Jacob Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jacoblaw.adv.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_.png\",\"datePublished\":\"2020-06-16T13:27:46+00:00\",\"dateModified\":\"2020-10-13T19:47:42+00:00\",\"description\":\"\u00c0 medida que novas e inovadoras tecnologias v\u00e3o evoluindo as novas rela\u00e7\u00f5es de trabalho se tornam mais din\u00e2micas e instant\u00e2neas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jacoblaw.adv.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_.png\",\"contentUrl\":\"https:\\\/\\\/jacoblaw.adv.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_.png\",\"width\":2240,\"height\":1260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jacoblaw.adv.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/#website\",\"url\":\"https:\\\/\\\/jacoblaw.adv.br\\\/\",\"name\":\"Jacob Law\",\"description\":\"| Advocacia para um mundo digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jacoblaw.adv.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/#organization\",\"name\":\"Jacob Law\",\"url\":\"https:\\\/\\\/jacoblaw.adv.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jacoblaw.adv.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/cropped-azulclaro.png\",\"contentUrl\":\"https:\\\/\\\/jacoblaw.adv.br\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/cropped-azulclaro.png\",\"width\":1920,\"height\":426,\"caption\":\"Jacob Law\"},\"image\":{\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jacoblaw.adv.br\\\/#\\\/schema\\\/person\\\/37f9a3bf0b21ecb1ab4f89d49225b2a7\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c92e3de55eefe1385386d673b9578e21bc4b4058fe6acd2c09b79bd1f3663f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c92e3de55eefe1385386d673b9578e21bc4b4058fe6acd2c09b79bd1f3663f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c92e3de55eefe1385386d673b9578e21bc4b4058fe6acd2c09b79bd1f3663f1?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"sameAs\":[\"https:\\\/\\\/jacoblaw.adv.br\"],\"url\":\"https:\\\/\\\/jacoblaw.adv.br\\\/en\\\/author\\\/Eduardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso? - Jacob Law","description":"\u00c0 medida que novas e inovadoras tecnologias v\u00e3o evoluindo as novas rela\u00e7\u00f5es de trabalho se tornam mais din\u00e2micas e instant\u00e2neas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/","og_locale":"en_US","og_type":"article","og_title":"Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso? - Jacob Law","og_description":"\u00c0 medida que novas e inovadoras tecnologias v\u00e3o evoluindo as novas rela\u00e7\u00f5es de trabalho se tornam mais din\u00e2micas e instant\u00e2neas.","og_url":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/","og_site_name":"Jacob Law","article_published_time":"2020-06-16T13:27:46+00:00","article_modified_time":"2020-10-13T19:47:42+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/jacoblaw.adv.br\/wp-content\/uploads\/2020\/10\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_-1024x576.png","type":"image\/png"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/#article","isPartOf":{"@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/"},"author":{"name":"Eduardo","@id":"https:\/\/jacoblaw.adv.br\/#\/schema\/person\/37f9a3bf0b21ecb1ab4f89d49225b2a7"},"headline":"Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso?","datePublished":"2020-06-16T13:27:46+00:00","dateModified":"2020-10-13T19:47:42+00:00","mainEntityOfPage":{"@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/"},"wordCount":1368,"commentCount":0,"publisher":{"@id":"https:\/\/jacoblaw.adv.br\/#organization"},"image":{"@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/#primaryimage"},"thumbnailUrl":"https:\/\/jacoblaw.adv.br\/wp-content\/uploads\/2020\/10\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_.png","keywords":["inova\u00e7\u00e3o","neg\u00f3cios digitais","novas rela\u00e7\u00f5es de trabalho","tecnologia"],"articleSection":["Mundo Digital","Neg\u00f3cios Digitais","Transforma\u00e7\u00e3o Digital","Tributa\u00e7\u00e3o Digital"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/","url":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/","name":"Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso? - Jacob Law","isPartOf":{"@id":"https:\/\/jacoblaw.adv.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/#primaryimage"},"image":{"@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/#primaryimage"},"thumbnailUrl":"https:\/\/jacoblaw.adv.br\/wp-content\/uploads\/2020\/10\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_.png","datePublished":"2020-06-16T13:27:46+00:00","dateModified":"2020-10-13T19:47:42+00:00","description":"\u00c0 medida que novas e inovadoras tecnologias v\u00e3o evoluindo as novas rela\u00e7\u00f5es de trabalho se tornam mais din\u00e2micas e instant\u00e2neas.","breadcrumb":{"@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/#primaryimage","url":"https:\/\/jacoblaw.adv.br\/wp-content\/uploads\/2020\/10\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_.png","contentUrl":"https:\/\/jacoblaw.adv.br\/wp-content\/uploads\/2020\/10\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_.png","width":2240,"height":1260},{"@type":"BreadcrumbList","@id":"https:\/\/jacoblaw.adv.br\/en\/novas-relacoes-de-trabalho-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jacoblaw.adv.br\/"},{"@type":"ListItem","position":2,"name":"Novas rela\u00e7\u00f5es de trabalho: o que tecnologia e inova\u00e7\u00e3o tem a ver com isso?"}]},{"@type":"WebSite","@id":"https:\/\/jacoblaw.adv.br\/#website","url":"https:\/\/jacoblaw.adv.br\/","name":"Jacob Law","description":"| Advocacia para um mundo digital","publisher":{"@id":"https:\/\/jacoblaw.adv.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jacoblaw.adv.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jacoblaw.adv.br\/#organization","name":"Jacob Law","url":"https:\/\/jacoblaw.adv.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jacoblaw.adv.br\/#\/schema\/logo\/image\/","url":"https:\/\/jacoblaw.adv.br\/wp-content\/uploads\/2020\/10\/cropped-azulclaro.png","contentUrl":"https:\/\/jacoblaw.adv.br\/wp-content\/uploads\/2020\/10\/cropped-azulclaro.png","width":1920,"height":426,"caption":"Jacob Law"},"image":{"@id":"https:\/\/jacoblaw.adv.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jacoblaw.adv.br\/#\/schema\/person\/37f9a3bf0b21ecb1ab4f89d49225b2a7","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5c92e3de55eefe1385386d673b9578e21bc4b4058fe6acd2c09b79bd1f3663f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c92e3de55eefe1385386d673b9578e21bc4b4058fe6acd2c09b79bd1f3663f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c92e3de55eefe1385386d673b9578e21bc4b4058fe6acd2c09b79bd1f3663f1?s=96&d=mm&r=g","caption":"Eduardo"},"sameAs":["https:\/\/jacoblaw.adv.br"],"url":"https:\/\/jacoblaw.adv.br\/en\/author\/Eduardo\/"}]}},"jetpack_featured_media_url":"https:\/\/jacoblaw.adv.br\/wp-content\/uploads\/2020\/10\/Novas-relacoes-de-trabalho_-o-que-tecnologia-e-inovacao-tem-a-ver-com-isso_.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/posts\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/comments?post=134"}],"version-history":[{"count":3,"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/posts\/134\/revisions"}],"predecessor-version":[{"id":285,"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/posts\/134\/revisions\/285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/media\/340"}],"wp:attachment":[{"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/media?parent=134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/categories?post=134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jacoblaw.adv.br\/en\/wp-json\/wp\/v2\/tags?post=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}